{"id":957,"date":"2021-04-26T07:42:09","date_gmt":"2021-04-26T06:42:09","guid":{"rendered":"http:\/\/nouzillyathletisme.fr\/?p=957"},"modified":"2021-05-09T17:37:10","modified_gmt":"2021-05-09T16:37:10","slug":"seances-pour-les-enfants-les-vendredis-30-avril-et-7-mai","status":"publish","type":"post","link":"https:\/\/nouzillyathletisme.fr\/index.php\/2021\/04\/26\/seances-pour-les-enfants-les-vendredis-30-avril-et-7-mai\/","title":{"rendered":"S\u00e9ances pour les enfants les vendredis 30 avril et 7 mai"},"content":{"rendered":"\n<p>Bonjour,<\/p>\n\n\n\n<p>Les deux prochains samedis \u00e9tant f\u00e9ri\u00e9s, nous pr\u00e9voyons de d\u00e9placer les s\u00e9ances d&rsquo;entrainements aux vendredis 30 avril et 07 mai de 17h15 \u00e0 18h30 pour tous les enfants du CP au CM2.<\/p>\n\n\n\n<p>Ces s\u00e9ances auront lieu au stade des marronniers.<\/p>\n\n\n\n<p>Afin d&rsquo;organiser les s\u00e9ances des enfants et pr\u00e9voir un nombre suffisant d&rsquo;encadrants pour maintenir des petits groupes, il vous est demand\u00e9 de compl\u00e9ter imp\u00e9rativement le sondage de pr\u00e9sence ou non de votre enfant dont vous trouverez le lien ci-dessous :<\/p>\n\n\n\n<p><a href=\"https:\/\/emea01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fframadate.org%2Fnouzillyathletisme&amp;data=04%7C01%7C%7C2e7d4b0893af4e61cb1608d90812f426%7C84df9e7fe9f640afb435aaaaaaaaaaaa%7C1%7C0%7C637549699756774642%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&amp;sdata=w6ZkOCb44%2FcRsKWyoS%2BvofXqjpo%2BbEQGzhPu0poXSZI%3D&amp;reserved=0\">Sondage &#8211; Pr\u00e9sence des enfants pour les vendredis (des CP au CM2) &#8211; Framadate<\/a><\/p>\n\n\n\n<p>Au d\u00e9but de la s\u00e9ance, Merci de vous faire noter sur la feuille de pr\u00e9sence.<\/p>\n\n\n\n<p>Sportivement<\/p>\n\n\n\n<p>Herv\u00e9<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bonjour, Les deux prochains samedis \u00e9tant f\u00e9ri\u00e9s, nous pr\u00e9voyons de d\u00e9placer les s\u00e9ances [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":959,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[4],"tags":[],"class_list":["post-957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/nouzillyathletisme.fr\/wp-content\/uploads\/2021\/04\/istockphoto-1080232360-612x612-1.jpg","jetpack_sharing_enabled":true,"jetpack_likes_enabled":false,"_links":{"self":[{"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/posts\/957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/comments?post=957"}],"version-history":[{"count":0,"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/posts\/957\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/media\/959"}],"wp:attachment":[{"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/media?parent=957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/categories?post=957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/nouzillyathletisme.fr\/index.php\/wp-json\/wp\/v2\/tags?post=957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}